{"id":1106575,"date":"2025-06-11T08:57:18","date_gmt":"2025-06-11T06:57:18","guid":{"rendered":"https:\/\/pokeriomokykla.com\/il-nuovo-galles-del-sud-ha-subito-una-perdita-di-217-miliardi-di-dollari-nel-primo-trimestre-del-2025-a-causa-delle-slot-machine"},"modified":"2026-05-11T03:21:21","modified_gmt":"2026-05-11T01:21:21","slug":"il-nuovo-galles-del-sud-ha-subito-una-perdita-di-217-miliardi-di-dollari-nel-primo-trimestre-del-2025-a-causa-delle-slot-machine","status":"publish","type":"post","link":"https:\/\/pokeriomokykla.com\/it\/il-nuovo-galles-del-sud-ha-subito-una-perdita-di-217-miliardi-di-dollari-nel-primo-trimestre-del-2025-a-causa-delle-slot-machine\/","title":{"rendered":"Il Nuovo Galles del Sud ha subito una perdita di 2,17 miliardi di dollari nel primo trimestre del 2025 a causa delle slot machine."},"content":{"rendered":"<p>Il governo del Nuovo Galles del Sud non ha intrapreso alcuna azione riguardo alla perdita di 2,17 miliardi di dollari dovuta alle slot machine nei primi tre mesi di quest'anno, nonostante un gruppo di beneficenza abbia sollecitato un inasprimento delle normative.<\/p><p>Un'indagine di &#8220;Wesley Mission&#8221; ha mostrato che nei primi tre mesi del 2025 sono stati persi il 5,7% in pi\u00f9 di denaro a causa delle slot machine rispetto allo stesso periodo del 2024. Secondo i dati dell'indagine, i residenti del Nuovo Galles del Sud perdono pi\u00f9 di 1 milione di dollari all'ora, cio\u00e8 quasi 24 milioni di dollari al giorno.<\/p><p>I residenti dei quartieri occidentali di Sydney hanno perso la maggior parte del denaro. In soli 90 giorni, nei 4924 poker machine del distretto di Canterbury e Bankstown sono stati persi quasi 186 milioni di dollari.<\/p><div class=\"wp-block-image\"><figure class=\"alignright size-full is-resized\"><img decoding=\"async\" width=\"674\" height=\"516\" src=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2025\/06\/image-13.jpg\" alt=\"Un residente del NSW gioca a una slot machine\" class=\"wp-image-1106559\" style=\"width:443px;height:auto\" srcset=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2025\/06\/image-13.jpg 674w, https:\/\/pokeriomokykla.com\/app\/uploads\/2025\/06\/image-13-300px-230px.jpg 300w, https:\/\/pokeriomokykla.com\/app\/uploads\/2025\/06\/image-13-294px-225px.jpg 294w, https:\/\/pokeriomokykla.com\/app\/uploads\/2025\/06\/image-13-157px-120px.jpg 157w, https:\/\/pokeriomokykla.com\/app\/uploads\/2025\/06\/image-13-609px-466px.jpg 609w\" sizes=\"(max-width: 674px) 100vw, 674px\" \/><figcaption class=\"wp-element-caption\">Un residente del NSW gioca a una slot machine<\/figcaption><\/figure><\/div><p>Questo equivale a pi\u00f9 di 2 milioni di dollari al giorno. Nello stesso periodo di tre mesi, le aree di Fairfield, Cumberland, Blacktown, Parramatta, Penrith, Campbelltown e Canterbury-Bankstown nel Sydney occidentale hanno perso quasi 766 milioni di dollari a causa delle slot machine.<\/p><p>Nel Sydney occidentale, le persone perdono circa 3200 dollari all'anno, afferma &#8220;Wesley Mission&#8221;, che fa parte del gruppo indipendente di esperti di riforma del gioco d'azzardo del governo del NSW.<\/p><div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/pokeriomokykla.com\/it\/il-nuovo-galles-del-sud-ha-subito-una-perdita-di-217-miliardi-di-dollari-nel-primo-trimestre-del-2025-a-causa-delle-slot-machine\/#Inattivita_del_governo_e_delusione_della_comunita\" >Inattivit\u00e0 del governo e delusione della comunit\u00e0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/pokeriomokykla.com\/it\/il-nuovo-galles-del-sud-ha-subito-una-perdita-di-217-miliardi-di-dollari-nel-primo-trimestre-del-2025-a-causa-delle-slot-machine\/#Appelli_per_riforme_piu_severe_del_gioco_dazzardo\" >Appelli per riforme pi\u00f9 severe del gioco d'azzardo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/pokeriomokykla.com\/it\/il-nuovo-galles-del-sud-ha-subito-una-perdita-di-217-miliardi-di-dollari-nel-primo-trimestre-del-2025-a-causa-delle-slot-machine\/#Promesse_politiche_e_responsabilita_pubblica\" >Promesse politiche e responsabilit\u00e0 pubblica<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Inattivita_del_governo_e_delusione_della_comunita\"><\/span>Inattivit\u00e0 del governo e delusione della comunit\u00e0<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Il direttore generale di &#8220;Wesley Mission&#8221;, Stu Cameron, ha esortato il governo statale ad agire e a inasprire immediatamente le normative sulle slot machine. Cameron ha affermato che, sebbene il governo abbia introdotto alcuni cambiamenti, questi non hanno avuto un impatto significativo.<\/p><p>Ha sottolineato che il danno causato dalle slot machine continua a crescere e le perdite aumentano ogni giorno. Se l'obiettivo era ridurre il danno del gioco d'azzardo, secondo lui, queste misure sono state insufficienti. Ha evidenziato che ora \u00e8 necessario avere il coraggio di agire con decisione, piuttosto che continuare a procrastinare.<\/p><p>In risposta, un portavoce del ministro del gioco d'azzardo e delle corse del Nuovo Galles del Sud, David Harris, ha affermato che il governo rimane impegnato a portare avanti riforme basate su prove.<\/p><p>Il loro obiettivo \u00e8 ridurre il danno del gioco d'azzardo, prevenire il riciclaggio di denaro, sostenere le comunit\u00e0 locali e creare posti di lavoro. Harris ha osservato che &#8220;<em>il cambiamento comportamentale richiede tempo<\/em>&#8221; e che questo \u00e8 l'obiettivo a lungo termine della loro strategia di riforma del gioco d'azzardo.<\/p><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Appelli_per_riforme_piu_severe_del_gioco_dazzardo\"><\/span>Appelli per riforme pi\u00f9 severe del gioco d'azzardo<span class=\"ez-toc-section-end\"><\/span><\/h2><p>Da quando \u00e8 salita al potere nel 2023, l'attuale amministrazione ha ridotto il limite delle slot machine nel Nuovo Galles del Sud di oltre 3000, riducendo cos\u00ec il numero totale di macchine in tutto lo stato.<\/p><p>Inoltre, il governo ha introdotto limiti di contante per le nuove macchine, ha investito 100 milioni di dollari in iniziative di riduzione del danno e ha aumentato il numero di ufficiali di gioco responsabile per rafforzare il supporto.<\/p><p>Nel frattempo, &#8220;Wesley Mission&#8221; ha esortato il governo statale a obbligare a spegnere le slot machine dalla mezzanotte alle 10 del mattino. Chiedono anche l'introduzione di una carta di gioco senza contanti con limiti di danno integrati e un controllo pi\u00f9 rigoroso del numero di macchine nelle zone ad alto rischio.<\/p><p>Cameronas ha detto: \u201eQueste non sono idee radicali; sono modi fondamentali per proteggere la salute pubblica.\u201c Ha aggiunto: \u201e<em>Il governo interverrebbe se le persone fossero gravemente colpite da droghe, alcol o strade non sicure. Le regole del gioco d'azzardo dovrebbero essere le stesse<\/em>.\u201c<\/p><!-- \/wp:post-content --><!-- wp:paragraph --><p>Invece, l'industria trae profitto e il governo fa poco per prevenire i danni. Uno studio di Wesley Mission ha anche rilevato che nel secondo trimestre del 2025 sono state utilizzate leggermente pi\u00f9 macchine da poker in tutto lo stato rispetto al primo trimestre del 2024.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Promesse_politiche_e_responsabilita_pubblica\"><\/span>Promesse politiche e responsabilit\u00e0 pubblica<span class=\"ez-toc-section-end\"><\/span><\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p>Il ministro ombra del gioco d'azzardo Kevin Anderson ha criticato il governo del Minnesota per l'inattivit\u00e0, affermando che prima delle elezioni statali aveva \u201epromesso grandi cose\u201c riguardo alla riforma delle macchine da poker, ma non ha mantenuto la promessa.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Anderson sostiene che i ritardi in questa regione sono <em>\u201esorprendenti\u201c e \u201emolto frustranti\u201c. \u201eI bar e i club con cui parlo sono stanchi di aspettare che il governo fornisca loro la certezza necessaria<\/em>.\u201c<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>A novembre, un gruppo non governativo ha elaborato un piano dettagliato per la riforma della regolamentazione delle macchine da poker. Il governo del Minnesota non ha risposto pubblicamente e il gruppo afferma che le discussioni sono in corso. <\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Poich\u00e9 le perdite delle macchine da poker continuano a crescere, sempre pi\u00f9 persone nel Nuovo Galles del Sud chiedono una leadership forte che dia priorit\u00e0 alla salute pubblica piuttosto che ai ricavi del gioco d'azzardo.<\/p><!-- \/wp:paragraph -->","protected":false},"excerpt":{"rendered":"<p>Il governo del Nuovo Galles del Sud non ha intrapreso&#8230;<\/p>\n","protected":false},"author":541,"featured_media":1106559,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1646,817],"tags":[],"class_list":["post-1106575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casino-news","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/posts\/1106575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/users\/541"}],"replies":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/comments?post=1106575"}],"version-history":[{"count":1,"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/posts\/1106575\/revisions"}],"predecessor-version":[{"id":1114609,"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/posts\/1106575\/revisions\/1114609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/media\/1106559"}],"wp:attachment":[{"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/media?parent=1106575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/categories?post=1106575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/it\/wp-json\/wp\/v2\/tags?post=1106575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}