{"id":789260,"date":"2021-01-29T16:15:31","date_gmt":"2021-01-29T14:15:31","guid":{"rendered":"https:\/\/pokeriomokykla.com\/zalgiris-baskonia-2021-01-29-eurolyga-maco-apzvalga"},"modified":"2026-05-11T05:46:19","modified_gmt":"2026-05-11T03:46:19","slug":"zalgiris-baskonia-2021-01-29-eurolyga-maco-apzvalga","status":"publish","type":"post","link":"https:\/\/pokeriomokykla.com\/fr\/baskonia-zalgiris-2021-789260","title":{"rendered":"\u017dalgiris &#8211; Baskonia, 2021-01-29 Euroleague, aper\u00e7u du match"},"content":{"rendered":"<h2><img decoding=\"async\" class=\"alignleft size-full wp-image-765190\" src=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/Grigonis.jpg\" alt=\"Grigonis\" width=\"1024\" height=\"683\" srcset=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/Grigonis.jpg 1024w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/Grigonis-300x200.jpg 300w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/Grigonis-768px-512px.jpg 768w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/Grigonis-180px-120px.jpg 180w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/Grigonis-700px-466px.jpg 700w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/h2>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/pokeriomokykla.com\/fr\/baskonia-zalgiris-2021-789260\/#Zalgiris\" >\u017dalgiris<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/pokeriomokykla.com\/fr\/baskonia-zalgiris-2021-789260\/#Baskonia\" >Baskonia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/pokeriomokykla.com\/fr\/baskonia-zalgiris-2021-789260\/#Prevision\" >Pr\u00e9vision<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/pokeriomokykla.com\/fr\/baskonia-zalgiris-2021-789260\/#Zalgiris_va_gagner_235_cote_betsafe\" >\u017dalgiris va gagner, 2,35 cote. betsafe<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Zalgiris\"><\/span>\u017dalgiris<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Kauno \u017dalgiris (13-9) entre dans ce match apr\u00e8s une victoire impressionnante contre l'\u00e9quipe de Valence. La fin facile du match a presque tourn\u00e9 au cauchemar, lorsqu'il restait 40 secondes et que l'\u00e9quipe menait de 7 points, Valence a pris l'avantage d'un point avec seulement 3 secondes restantes, apr\u00e8s un tir \u00e0 trois points r\u00e9ussi de S. Van Rossom. Cependant, Marius Grigonis a d\u00e9montr\u00e9 pourquoi il est consid\u00e9r\u00e9 comme l'un des meilleurs joueurs dans les moments d\u00e9cisifs cette saison et, avec un tir difficile \u00e0 deux points, a arrach\u00e9 la victoire pour \u017dalgiris.<\/p>\n<p>Le match contre Valence est vraiment ambigu : d'une part, on peut dire que l'\u00e9quipe a montr\u00e9 une mentalit\u00e9 de gagnant et a r\u00e9ussi \u00e0 cl\u00f4turer un match pratiquement perdu, mais d'autre part, il est \u00e9vident qu'avec +7 points et 40 secondes \u00e0 jouer, il aurait \u00e9t\u00e9 possible de jouer plus calmement et d'\u00e9viter une fin de match dramatique. Dans ce match, on a pu voir \u00e0 quel point \u017dalgiris bougeait bien en attaque : seulement 17 tirs \u00e0 trois points tent\u00e9s, dont 9 r\u00e9ussis, ce qui montre que les tirs ont \u00e9t\u00e9 pris uniquement \u00e0 partir de bonnes positions et que les tirs \u00e0 trois points n'ont pas \u00e9t\u00e9 abus\u00e9s.<\/p>\n<p>Apr\u00e8s le match contre Valence, dans lequel J. Lauvergne a r\u00e9alis\u00e9 un double-double (13 pts, 12 rebonds), le contrat avec le joueur a \u00e9t\u00e9 prolong\u00e9. On peut se rappeler la derni\u00e8re fois qu'un contrat a \u00e9t\u00e9 prolong\u00e9 en milieu de saison avec B. Davies. Apr\u00e8s la prolongation du contrat, le joueur a commenc\u00e9 \u00e0 montrer de meilleurs r\u00e9sultats et est devenu un leader \u00e9vident de l'\u00e9quipe. Il sera int\u00e9ressant de voir si la prolongation du contrat aura un impact sur le jeu du Fran\u00e7ais.<\/p>\n<h2><img decoding=\"async\" class=\"alignleft size-full wp-image-765189\" src=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/rokas-giedraitis-86196525.jpg\" alt=\"Rokas GIedraitis Baskonia\" width=\"1024\" height=\"682\" srcset=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/rokas-giedraitis-86196525.jpg 1024w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/rokas-giedraitis-86196525-300x200.jpg 300w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/rokas-giedraitis-86196525-768px-512px.jpg 768w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/rokas-giedraitis-86196525-180px-120px.jpg 180w, https:\/\/pokeriomokykla.com\/app\/uploads\/2021\/01\/rokas-giedraitis-86196525-700px-466px.jpg 700w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/h2>\n<h2><span class=\"ez-toc-section\" id=\"Baskonia\"><\/span>Baskonia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Baskonia (9-13) joue de mani\u00e8re tr\u00e8s irr\u00e9guli\u00e8re cette saison : quelques victoires cons\u00e9cutives sont suivies de quelques d\u00e9faites cons\u00e9cutives et l'histoire se r\u00e9p\u00e8te. Actuellement, les Basques ont une s\u00e9rie de 4 d\u00e9faites cons\u00e9cutives (76-96 Ulker; 82-91 Maccabi; 77-84 Alba; 77-83 Lyon-Villeurbanne). Les deux derniers matchs contre Alba et Asvel soul\u00e8vent beaucoup de questions, tandis que les d\u00e9faites contre les \u00e9quipes potentiellement plus fortes d'Ulker et de Maccabi peuvent en partie \u00eatre justifi\u00e9es. Alba occupe actuellement la 15e place au classement, tandis que l'\u00e9quipe d'Asvel est 14e. L'\u00e9quipe manque manifestement de stabilit\u00e9 et d'un leader clair, une position que R. Giedraitis a tent\u00e9 d'occuper au d\u00e9but de la saison, mais r\u00e9cemment, Rokas a \u00e9galement eu plus de difficult\u00e9s.<\/p>\n<p>Une agr\u00e9able surprise dans l'\u00e9quipe de Baskonia cette saison a \u00e9t\u00e9 l'Italien A. Polonara, qui est parmi les meilleurs marqueurs de l'\u00e9quipe \u00e0 chaque match et \u00e9galement parmi les joueurs qui r\u00e9cup\u00e8rent le plus de rebonds. Bien que Polonara n'ait pas un tir stable \u00e0 trois points, ce joueur de 29 ans, jouant aux positions d'ailier fort et d'ailier, utilise son athl\u00e9tisme et se bat bien sous le panier.<\/p>\n<p>Il est difficile de dire d'o\u00f9 viennent les plus gros probl\u00e8mes de Baskonia cette saison : on peut dire que le staff technique ne fait pas son travail ou que l'\u00e9quipe est faible, mais en essence, l'\u00e9quipe semble vraiment capable de se battre pour entrer dans le top 8 et de montrer de meilleurs r\u00e9sultats que ceux que nous voyons actuellement.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Prevision\"><\/span>Pr\u00e9vision<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Le favori de ce match selon les bookmakers est le club de Baskonia, avec une cote de 1,6 pour la victoire, tandis que pour \u017dalgiris, elle est de 2,35. En regardant les deux \u00e9quipes et leurs performances r\u00e9centes, il est assez \u00e9vident que \u017dalgiris traverse une p\u00e9riode bien meilleure et entrera dans le match avec des sentiments plus positifs. Baskonia est une \u00e9quipe dangereuse, surtout \u00e0 domicile, mais \u017dalgiris est injustement sous-estim\u00e9 dans ce match et, selon les cotes propos\u00e9es, parier sur la victoire de \u017dalgiris a de la valeur.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Zalgiris_va_gagner_235_cote_betsafe\"><\/span>\u017dalgiris va gagner, 2,35 cote. betsafe<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Si vous \u00eates int\u00e9ress\u00e9 \u00e0 suivre toutes nos analyses, vous pouvez les trouver <a href=\"https:\/\/pokeriomokykla.com\/statymu-prognozes-nemokami-statymai\">ici<\/a>. Nous vous recommandons \u00e9galement de visiter notre page Facebook <a href=\"https:\/\/www.facebook.com\/groups\/RimtiStatymai\" target=\"_blank\" rel=\"noopener\">Rimti Statymai<\/a><\/p>\n<h3 style=\"text-align: center\"><strong><b>TOP La\u017eyb\u0173 kontoros Eurolygos statymams<\/b><\/strong><\/h3>\n\n<div class='widget-card placeholder--card'\n     data-source-gql='https:\/\/scg-new-live.stellate.sh\/'\n     data-source-widgetjs='https:\/\/widget.affprojects.com\/widget.js'\n     data-shortcode='widget-card'\n     data-shortcode-text='[top-bookmakers-for-post]'\n     data-props='{\n\"show_more_button\":true,\n\"show_more_button_text\":\"Show More Bookmakers\",\n\"show_more_text\":false,\n\"show_less_text\":false,\n\"vpn_notification\":false,\n\"show_more_items_amount\":null,\n\"scrollable\":\"always\",\n\"violet_bonus_text\":true,\n\"ab_testing_show_more_button_rework\":true\n}'\n     data-queries='{\n\"type\":\"TOP-Betting\",\n\"limit\":10,\n\"mobile_limit\":10,\n\"show_new\":1,\n\"button_text_type\":\"TOP\",\n\"language\":\"fr\",\n\"project\":\"PM\",\n\"page\":1\n}'\n     ><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>\u017dalgiris Kauno \u017dalgiris (13-9) entre dans ce match apr\u00e8s une&#8230;<\/p>\n","protected":false},"author":7495,"featured_media":765190,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8734,8129,8727,8135,2720,2648,2390,2767,1],"tags":[],"class_list":["post-789260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahis-tahminleri","category-bahisler","category-basketbol-bahisleri","category-eurolygos-bahisleri","category-paris","category-paris-de-basket-ball","category-paris-euroleague","category-previsions-de-paris","category-uncategorized-lt"],"acf":[],"_links":{"self":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts\/789260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/users\/7495"}],"replies":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/comments?post=789260"}],"version-history":[{"count":3,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts\/789260\/revisions"}],"predecessor-version":[{"id":1098859,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts\/789260\/revisions\/1098859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/media\/765190"}],"wp:attachment":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/media?parent=789260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/categories?post=789260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/tags?post=789260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}