{"id":787288,"date":"2015-09-17T20:29:58","date_gmt":"2015-09-17T18:29:58","guid":{"rendered":"https:\/\/pokeriomokykla.com\/sunkus-profesionalaus-pokerio-zaidejo-gyvenimas"},"modified":"2026-05-11T07:35:19","modified_gmt":"2026-05-11T05:35:19","slug":"sunkus-profesionalaus-pokerio-zaidejo-gyvenimas","status":"publish","type":"post","link":"https:\/\/pokeriomokykla.com\/fr\/la-dure-vie-dun-joueur-de-poker-professionnel","title":{"rendered":"La vie difficile d&#8217;un joueur de poker professionnel : Matthew \u00ab mindcirkus \u00bb Wheat"},"content":{"rendered":"<h4 class=\"wp-block-heading has-text-align-center\"><img decoding=\"async\" class=\"size-full wp-image-764067 alignnone\" src=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2015\/09\/Matthew-%E2%80%9Emindcirkus.jpg\" alt=\"\" width=\"512\" height=\"363\"><\/h4>\n<p>Matthew \u201emindcirkus\u201c Wheat est un <a href=\"\/fr\/devenir-professionnel\">joueur de poker professionnel<\/a>. Il est pass\u00e9 avec succ\u00e8s du \u00ab NLHE \u00bb au \u00ab PLO \u00bb et en 2010, il a atteint la table finale en jouant au \u00ab WSOP Events Nr. 55, $10.000 PLO Championship \u00bb.<\/p>\n<p>La plupart des gens pensent qu'un professionnel du poker est un gars qui s'assoit dans un casino et gagne ainsi des tas d'argent.<\/p>\n<p>La r\u00e9alit\u00e9 est un peu diff\u00e9rente, pour laquelle conviendrait probablement une expression entendue plus d'une fois : \u00ab It\u2019s a hard way to make an easy living \u00bb.<\/p>\n<p>Pour clarifier ce que cela signifie, je demande volontiers aux gens : \u00ab Peux-tu imaginer ce que \u00e7a fait de travailler dur toute la journ\u00e9e et de perdre finalement $10.000 ? Cela m'arrive constamment \u00bb.<\/p>\n<p>Le sentiment de mettre beaucoup de travail et de perdre quand m\u00eame beaucoup d'argent ne peut \u00eatre compris que si on l'a v\u00e9cu soi-m\u00eame. Jouer au poker \u00e0 hautes limites est aussi stressant que piloter un avion dans des conditions extr\u00eames.<\/p>\n<p>Un autre probl\u00e8me pour les joueurs de poker est qu'ils ne sont pas respect\u00e9s par la soci\u00e9t\u00e9 en raison de leur profession. La plupart des parents sont horrifi\u00e9s lorsque leur enfant dit qu'il veut quitter son travail ou ses \u00e9tudes pour devenir joueur de poker professionnel.<\/p>\n<p>Il est vrai qu'il peut y avoir diff\u00e9rentes perspectives du point de vue moral : quand on gagne de l'argent \u00e0 la table contre des joueurs plus faibles et quand on utilise l'intelligence et travaille dur pour devenir un joueur d'\u00e9lite.<\/p>\n<p>Quiconque est un peu familier avec le poker \u00e0 hautes limites et l'enseignement sup\u00e9rieur comprend que ce jeu n\u00e9cessite d'\u00eatre plus intellectuel et d'\u00e9tudier davantage que pour obtenir un doctorat.<\/p>\n<h3 class=\"wp-block-heading\">Il faut y consacrer beaucoup de temps si l'on veut vivre de cette activit\u00e9<\/h3>\n<p>Au d\u00e9but du poker en ligne, il \u00e9tait possible de gagner beaucoup d'argent sans beaucoup d'exp\u00e9rience et sans connaissances approfondies. Mais aujourd'hui, il faut y consacrer beaucoup de temps et bien s\u00fbr \u00eatre talentueux si l'on veut vivre de cette activit\u00e9.<\/p>\n<p>Celui qui veut devenir un bon joueur est pr\u00eat \u00e0 y consacrer beaucoup de temps et de travail, a pratiquement des possibilit\u00e9s illimit\u00e9es tant en termes de revenus que de sens du travail.<\/p>\n<p>Cependant, en consid\u00e9rant le poker comme une profession, certaines circonstances apparaissent, c'est-\u00e0-dire que l'argent prend une toute autre valeur. Un avocat qui gagne $500 par heure \u00e9value cet argent tr\u00e8s diff\u00e9remment d'un joueur de poker qui gagne \u00e9galement $500 par heure.<\/p>\n<p>Cela s'explique assez simplement : L'avocat re\u00e7oit $500 pour chaque heure de travail. S'il veut acheter quelque chose pour $1000, il doit travailler deux heures pour cela.<\/p>\n<p>Un joueur de poker qui gagne en moyenne $500 par heure doit jouer \u00e0 des limites vraiment \u00e9lev\u00e9es, o\u00f9 il peut facilement perdre des sommes entre $10.000 et $100.000 en une heure. Quand l'argent vient et part si rapidement, il devient particuli\u00e8rement difficile de se comporter de mani\u00e8re mod\u00e9r\u00e9e dans de telles situations.<\/p>\n<p>Si un joueur s'am\u00e9liore constamment et apprend de ses erreurs, il commence \u00e0 mieux contr\u00f4ler l'argent avec le temps, mais le probl\u00e8me ne dispara\u00eet pas, il est donc n\u00e9cessaire de rester prudent.<\/p>\n<h3 class=\"wp-block-heading\">Important : trouver son format de poker<\/h3>\n<p>Quiconque veut tirer ses revenus principaux du poker doit constamment r\u00e9fl\u00e9chir \u00e0 quelles <a href=\"http:\/\/pokeriomokykla.com\/video-pamokos\/pokerio-rusys\">variantes de poker<\/a> apportent les plus grands gains. Cela signifie qu'il faut constamment varier. J'ai vu plus d'un joueur de poker faire l'erreur de rester jouer au m\u00eame endroit apr\u00e8s une victoire.<\/p>\n<p>Le jeu de poker change constamment, l\u00e0 o\u00f9 il \u00e9tait facile de gagner de l'argent, il est maintenant devenu beaucoup plus difficile. Par exemple, en ao\u00fbt 2007, je jouais sur 20 tables de $1\/$2 \u00ab NLHE \u00bb. \u00c0 l'\u00e9poque, je gagnais, comme d'autres bons joueurs, en moyenne $15.000 par mois. Et cela \u00e9tait possible avec des comp\u00e9tences et des connaissances qui seraient maintenant consid\u00e9r\u00e9es comme faibles.<\/p>\n<p>Je continuais \u00e0 jouer le m\u00eame type de jeu jusqu'\u00e0 ce que mes revenus commencent \u00e0 diminuer et que ces derni\u00e8res ann\u00e9es, cela devienne insupportablement difficile.<\/p>\n<p>J'ai reconnu les progr\u00e8s des joueurs de poker seulement au d\u00e9but de 2009. J'ai alors commenc\u00e9 \u00e0 consacrer beaucoup de temps \u00e0 l'apprentissage du \u00ab 6-max Pot Limit Omaha \u00bb. Au d\u00e9but, \u00e7a ne se passait pas bien et je perdais constamment de l'argent, mais avec le temps, j'ai commenc\u00e9 \u00e0 gagner plus que lorsque je jouais au \u00ab NLHE \u00bb.<\/p>\n<p>Aujourd'hui, jouer au \u00ab 6-max Pot Limit Omaha \u00bb est aussi difficile que le \u00ab NLHE \u00bb. Bien que je sois toujours l'un des meilleurs joueurs et que je gagne beaucoup d'argent, j'apprends toujours d'autres types de jeux pour \u00eatre pr\u00eat quand le moment viendra.<\/p>\n<address><span style=\"color: #888888;\">Auteur : Matthew Wheat, cardrunners.com<\/span><\/address>\n<address><span style=\"color: #888888;\">Emprunt\u00e9 de <span style=\"text-decoration: underline;\"><strong><a href=\"http:\/\/www.pokerzeit.com\/leben-als-pokerprofi-1\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #888888; text-decoration: underline;\">http:\/\/www.pokerzeit.com\/leben-als-pokerprofi-1<\/span><\/a><\/strong><\/span><\/span><\/address>\n<h2 class=\"wp-block-heading\">O\u00f9 est-il pr\u00e9f\u00e9rable de jouer au poker ?<\/h2>\n\n<div class='widget-card placeholder--card'\n     data-source-gql='https:\/\/scg-new-live.stellate.sh\/'\n     data-source-widgetjs='https:\/\/widget.affprojects.com\/widget.js'\n     data-shortcode='widget-card'\n     data-shortcode-text='[top-poker-rooms-for-post]'\n     data-props='{\n\"show_more_button\":true,\n\"show_more_button_text\":\"Show More Bookmakers\",\n\"show_more_text\":false,\n\"show_less_text\":false,\n\"vpn_notification\":false,\n\"show_more_items_amount\":null,\n\"scrollable\":\"always\",\n\"violet_bonus_text\":true,\n\"ab_testing_show_more_button_rework\":true\n}'\n     data-queries='{\n\"type\":\"TOP-Poker\",\n\"limit\":10,\n\"mobile_limit\":10,\n\"show_new\":1,\n\"button_text_type\":\"TOP\",\n\"language\":\"fr\",\n\"project\":\"PM\",\n\"page\":1\n}'\n     ><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Matthew \u201emindcirkus\u201c Wheat est un joueur de poker professionnel. Il&#8230;<\/p>\n","protected":false},"author":72,"featured_media":764067,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8496,8511,2481,2480,1],"tags":[],"class_list":["post-787288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-poker-stratejisi","category-psikoloji-tr","category-psychologie","category-strategie-de-poker","category-uncategorized-lt"],"acf":[],"_links":{"self":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts\/787288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/comments?post=787288"}],"version-history":[{"count":4,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts\/787288\/revisions"}],"predecessor-version":[{"id":1114867,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/posts\/787288\/revisions\/1114867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/media\/764067"}],"wp:attachment":[{"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/media?parent=787288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/categories?post=787288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/fr\/wp-json\/wp\/v2\/tags?post=787288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}