{"id":784719,"date":"2017-09-29T13:50:47","date_gmt":"2017-09-29T11:50:47","guid":{"rendered":"https:\/\/pokeriomokykla.com\/pokeriomokykla-com-knockout-festival-regresa-al-olympic-casino-del-8-al-15-de-octubre"},"modified":"2026-05-11T11:27:16","modified_gmt":"2026-05-11T09:27:16","slug":"pokeriomokykla-com-knockout-festival-regresa-al-olympic-casino-del-8-al-15-de-octubre","status":"publish","type":"post","link":"https:\/\/pokeriomokykla.com\/es\/pokerschool-com-festival-knockout-olympic-casino-casino-octubre-8-15","title":{"rendered":"\u00a1Pokeriomokykla.com Knockout Festival regresa a Olympic Casino del 8 al 15 de octubre!"},"content":{"rendered":"<p>Po vasaros atostog\u0173 stipriai atsinaujinusi, patobul\u0117jusi ir padidinus\u012f komandos sud\u0117t\u012f PokerioMokykla.com gr\u012f\u017eta ir \u012f Live pokerio aren\u0105. Pristatome jau 3-i\u0105 savo vardin\u0119 Knock-out turnyr\u0173 serij\u0105 Olympic Casino. Visi turnyrai vyks \u201eknockout\u201c principu, kitaip tariant u\u017e kiekvien\u0105 eliminuot\u0105 \u017eaid\u0117j\u0105 j\u016bs i\u0161 karto gausite pinigin\u012f priz\u0105. Visi serijos turnyrai vyks Olympic Casino Lietuva adresu &#8211; Konstitucijos pr. 20, Vilnius.\n<\/p>\n<p align=\"left\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-744396\" src=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2017\/09\/K.O-pokernews-660x438.jpg\" alt=\"\" width=\"660\" height=\"438\" srcset=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2017\/09\/K.O-pokernews-660x438.jpg 660w, https:\/\/pokeriomokykla.com\/app\/uploads\/2017\/09\/K.O-pokernews-660x438-300x199.jpg 300w, https:\/\/pokeriomokykla.com\/app\/uploads\/2017\/09\/K.O-pokernews-660x438-181px-120px.jpg 181w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/><\/p>\n<p>Kaip tikriausiai pamenate, PokerioMokykla.com pirmoji Lietuvoje suorganizavo Knock-out festival\u012f 2016 liep\u0105. D\u017eiaugiam\u0117s, kad gyvas pokeris Lietuvoje sulaukia vis didesnio susidom\u0117jimo. O mes savo ruo\u017etu \u0161\u012fkart pristatysime dvi naujoves, kurios populiarum\u0105, tikim\u0117s, tik dar labiau padidins.<\/p>\n<p>Pirmoji organizacin\u0117 \u2013 kartu su savo partneriais Spinumokykla.com nusprend\u0117me pasi\u016blyti Jums Live streamus\/tiesiogines transliacijas i\u0161 serijos turnyr\u0173! B\u016bsite pagrindini\u0173 \u012fvyki\u0173 liudininkais: ne tik gal\u0117site skaityti apie turnyr\u0173 eig\u0105 live reporta\u017euose, bet ir i\u0161girsti naujienas i\u0161 pirm\u0173 l\u016bp\u0173 video formatu: pa\u017eadame daug mini-interviu i\u0161 veiksmo s\u016bkurio!<\/p>\n<p>Antroji naujiena \u2013 pristatysime Lietuvoje dar nebandyt\u0105 turnyro format\u0105, kuris tur\u0117t\u0173 sugeneruoti tiek daug veiksmo kiek niekada nebuvo! \u201eMad Money\u201d pavadintas turnyras tur\u0117s 2x didesn\u012f Knock-out\u0105 u\u017e tai kas keliaus \u012f prizin\u012f fond\u0105: 100 EUR u\u017e galv\u0105, 50 EUR \u012f fond\u0105. Kadangi paskutiniai m\u016bs\u0173 festivaliai mu\u0161\u0117 dalyvi\u0173 skai\u010di\u0173 rekordus, nebejojame, kad solidus prizas lauks nugal\u0117tojo, kadangi \u012fsipirkti pakartotinai \u012f \u0161io tipo turnyr\u0105 ypatingai apsimoka (kaip ir kovoti d\u0117l kiekvieno i\u0161metimo)! O daugiausiai knock-out'\u0173 surinkusiam \u0161iame turnyre \u2013 specialus PokerioMokykla.com \u012fsteigtas prizas.<\/p>\n<p>Susitiksime prie stal\u0173 ir s\u0117km\u0117s dalyvaujantiems!<\/p>\n<p><strong>Pilnas Knockout Festival turnyr\u0173 tvarkara\u0161tis:<\/strong><\/p>\n\n<table id=\"tablepress-2\" class=\"tablepress tablepress-id-2 tablepress-responsive\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Data<\/th><th class=\"column-2\">Laikas<\/th><th class=\"column-3\">Pavadinimas<\/th><th class=\"column-4\">\u012epirka<\/th><th class=\"column-5\">Informacija<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">Spalio 8 d.<\/td><td class=\"column-2\">18:00<\/td><td class=\"column-3\">Warm-Up<\/td><td class=\"column-4\">50+10+6 = 66 EUR<\/td><td class=\"column-5\">Bounty 10\u20ac, Starting Stack 10K, Levels 25min., Late Registration and Re-entries available 8 levels<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">Spalio 9 d.<\/td><td class=\"column-2\">18:00<\/td><td class=\"column-3\">Warm-Up 2<\/td><td class=\"column-4\">70+20+10 = 100 EUR<\/td><td class=\"column-5\">Bounty 20\u20ac, Starting Stack 10K, Levels 25min., Late Registration and Re-entries available 8 levels<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">Spalio 10 d.<\/td><td class=\"column-2\">18:00<\/td><td class=\"column-3\">Mad Money<\/td><td class=\"column-4\">50+100+15 = 165 EUR<\/td><td class=\"column-5\">Bounty 100\u20ac, Starting Stack 15K, Levels 30min., Late Registration and Re-entries available 8 levels<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">Spalio 11 d.<\/td><td class=\"column-2\">18:00<\/td><td class=\"column-3\">Win The Button<\/td><td class=\"column-4\">100+35+15 = 150 EUR<\/td><td class=\"column-5\">Bounty 35\u20ac, Starting Stack 15K, Levels 30min., Late Registration and Re-entries available 8 levels<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">Spalio 12 d.<\/td><td class=\"column-2\">18:00<\/td><td class=\"column-3\">Turbo<\/td><td class=\"column-4\">75+25+10 = 110 EUR<\/td><td class=\"column-5\">Bounty 50\u20ac, Starting Stack 20K, Levels 15min., Late Registration and Re-entries available 12 levels<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">Spalio 13 d.<\/td><td class=\"column-2\">18:00<\/td><td class=\"column-3\">Main Event Day 1<\/td><td class=\"column-4\">200+100+30 = 330 EUR<\/td><td class=\"column-5\">Bounty 100\u20ac, Starting Stack 20K, Levels 40min., Late Registration and Re-entries available till the start of Day 2, playing 11 levels<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">Spalio 14 d.<\/td><td class=\"column-2\">16:00<\/td><td class=\"column-3\">Main Event Day 2<\/td><td class=\"column-4\">-<\/td><td class=\"column-5\">Till Start<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">Spalio 15 d.<\/td><td class=\"column-2\">18:00<\/td><td class=\"column-3\">closed VIP event for team members and friends<\/td><td class=\"column-4\">30+15+5 = 50 EUR<\/td><td class=\"column-5\">TBD<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<p><strong>Strukt\u016bra Main Event'ui:<\/strong><\/p>\n\n<table id=\"tablepress-3\" class=\"tablepress tablepress-id-3 tablepress-responsive\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Lygis<\/th><th class=\"column-2\">Blind'ai<\/th><th class=\"column-3\">Ante<\/th><th class=\"column-4\">Trukm\u0117<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">25\/50<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">50\/100<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">75\/150<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">100\/200<\/td><td class=\"column-3\">25<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">150\/300<\/td><td class=\"column-3\">25<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">200\/400<\/td><td class=\"column-3\">50<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">250\/500<\/td><td class=\"column-3\">50<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">300\/600<\/td><td class=\"column-3\">75<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">400\/800<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">500\/1000<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">600\/1200<\/td><td class=\"column-3\">200<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">800\/1600<\/td><td class=\"column-3\">200<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">1000\/2000<\/td><td class=\"column-3\">300<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-15 odd\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">1200\/2400<\/td><td class=\"column-3\">300<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-16 even\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">1500\/3000<\/td><td class=\"column-3\">400<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-17 odd\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">2000\/4000<\/td><td class=\"column-3\">400<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-18 even\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">2500\/5000<\/td><td class=\"column-3\">500<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-19 odd\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">3000\/6000<\/td><td class=\"column-3\">500<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-20 even\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">4000\/8000<\/td><td class=\"column-3\">1000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-21 odd\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">5000\/10000<\/td><td class=\"column-3\">1000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-22 even\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">6000\/12000<\/td><td class=\"column-3\">1000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-23 odd\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">8000\/16000<\/td><td class=\"column-3\">2000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-24 even\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">10000\/20000<\/td><td class=\"column-3\">2000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-25 odd\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">12000\/24000<\/td><td class=\"column-3\">3000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-26 even\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">15000\/30000<\/td><td class=\"column-3\">4000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-27 odd\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">20000\/40000<\/td><td class=\"column-3\">4000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-28 even\">\n\t<td class=\"column-1\">27<\/td><td class=\"column-2\">25000\/50000<\/td><td class=\"column-3\">5000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-29 odd\">\n\t<td class=\"column-1\">28<\/td><td class=\"column-2\">30000\/60000<\/td><td class=\"column-3\">5000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-30 even\">\n\t<td class=\"column-1\">29<\/td><td class=\"column-2\">40000\/80000<\/td><td class=\"column-3\">10000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-31 odd\">\n\t<td class=\"column-1\">30<\/td><td class=\"column-2\">50000\/100000<\/td><td class=\"column-3\">10000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<p><strong>Strukt\u016bra likusiems turnyrams:<\/strong><\/p>\n\n<table id=\"tablepress-4\" class=\"tablepress tablepress-id-4 tablepress-responsive\">\n<thead>\n<tr class=\"row-1 odd\">\n\t<th class=\"column-1\">Lygis<\/th><th class=\"column-2\">Blind'ai<\/th><th class=\"column-3\">Ante<\/th><th class=\"column-4\">Trukm\u0117<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-hover\">\n<tr class=\"row-2 even\">\n\t<td class=\"column-1\">1<\/td><td class=\"column-2\">25\/50<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-3 odd\">\n\t<td class=\"column-1\">2<\/td><td class=\"column-2\">50\/100<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-4 even\">\n\t<td class=\"column-1\">3<\/td><td class=\"column-2\">75\/150<\/td><td class=\"column-3\"><\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-5 odd\">\n\t<td class=\"column-1\">4<\/td><td class=\"column-2\">100\/200<\/td><td class=\"column-3\">25<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-6 even\">\n\t<td class=\"column-1\">5<\/td><td class=\"column-2\">150\/300<\/td><td class=\"column-3\">25<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-7 odd\">\n\t<td class=\"column-1\">6<\/td><td class=\"column-2\">200\/400<\/td><td class=\"column-3\">50<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-8 even\">\n\t<td class=\"column-1\">7<\/td><td class=\"column-2\">300\/600<\/td><td class=\"column-3\">75<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-9 odd\">\n\t<td class=\"column-1\">8<\/td><td class=\"column-2\">400\/800<\/td><td class=\"column-3\">100<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-10 even\">\n\t<td class=\"column-1\">9<\/td><td class=\"column-2\">600\/1200<\/td><td class=\"column-3\">200<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-11 odd\">\n\t<td class=\"column-1\">10<\/td><td class=\"column-2\">800\/1600<\/td><td class=\"column-3\">200<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-12 even\">\n\t<td class=\"column-1\">11<\/td><td class=\"column-2\">1000\/2000<\/td><td class=\"column-3\">300<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-13 odd\">\n\t<td class=\"column-1\">12<\/td><td class=\"column-2\">1200\/2400<\/td><td class=\"column-3\">300<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-14 even\">\n\t<td class=\"column-1\">13<\/td><td class=\"column-2\">1500\/3000<\/td><td class=\"column-3\">400<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-15 odd\">\n\t<td class=\"column-1\">14<\/td><td class=\"column-2\">2000\/4000<\/td><td class=\"column-3\">400<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-16 even\">\n\t<td class=\"column-1\">15<\/td><td class=\"column-2\">3000\/6000<\/td><td class=\"column-3\">500<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-17 odd\">\n\t<td class=\"column-1\">16<\/td><td class=\"column-2\">4000\/8000<\/td><td class=\"column-3\">1000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-18 even\">\n\t<td class=\"column-1\">17<\/td><td class=\"column-2\">6000\/12000<\/td><td class=\"column-3\">1000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-19 odd\">\n\t<td class=\"column-1\">18<\/td><td class=\"column-2\">8000\/16000<\/td><td class=\"column-3\">2000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-20 even\">\n\t<td class=\"column-1\">19<\/td><td class=\"column-2\">10000\/20000<\/td><td class=\"column-3\">2000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-21 odd\">\n\t<td class=\"column-1\">20<\/td><td class=\"column-2\">12000\/24000<\/td><td class=\"column-3\">3000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-22 even\">\n\t<td class=\"column-1\">21<\/td><td class=\"column-2\">15000\/30000<\/td><td class=\"column-3\">4000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-23 odd\">\n\t<td class=\"column-1\">22<\/td><td class=\"column-2\">20000\/40000<\/td><td class=\"column-3\">4000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-24 even\">\n\t<td class=\"column-1\">23<\/td><td class=\"column-2\">25000\/50000<\/td><td class=\"column-3\">5000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-25 odd\">\n\t<td class=\"column-1\">24<\/td><td class=\"column-2\">30000\/60000<\/td><td class=\"column-3\">5000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-26 even\">\n\t<td class=\"column-1\">25<\/td><td class=\"column-2\">40000\/80000<\/td><td class=\"column-3\">10000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<tr class=\"row-27 odd\">\n\t<td class=\"column-1\">26<\/td><td class=\"column-2\">50000\/100000<\/td><td class=\"column-3\">10000<\/td><td class=\"column-4\">40 min.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n","protected":false},"excerpt":{"rendered":"<p>Po vasaros atostog\u0173 stipriai atsinaujinusi, patobul\u0117jusi ir padidinus\u012f komandos sud\u0117t\u012f&#8230;<\/p>\n","protected":false},"author":3885,"featured_media":744396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,2398,1673],"tags":[],"class_list":["post-784719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized-lt","category-noticias","category-sin-categorizar-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts\/784719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/users\/3885"}],"replies":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/comments?post=784719"}],"version-history":[{"count":3,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts\/784719\/revisions"}],"predecessor-version":[{"id":1102724,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts\/784719\/revisions\/1102724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/media\/744396"}],"wp:attachment":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/media?parent=784719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/categories?post=784719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/tags?post=784719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}