{"id":784046,"date":"2019-11-09T19:14:35","date_gmt":"2019-11-09T17:14:35","guid":{"rendered":"https:\/\/pokeriomokykla.com\/atp-next-gen-finalas-alex-de-minaur-jannik-sinner"},"modified":"2026-05-11T10:51:18","modified_gmt":"2026-05-11T08:51:18","slug":"atp-next-gen-finalas-alex-de-minaur-jannik-sinner","status":"publish","type":"post","link":"https:\/\/pokeriomokykla.com\/es\/atp-next-gen-final-alex-de-minaur-jannik-sinner-784046","title":{"rendered":"ATP Next Gen Final, Alex De Minaur &#8211; Jannik Sinner"},"content":{"rendered":"<h2><img decoding=\"async\" class=\"alignleft size-full wp-image-759769\" src=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/alex-de-minaur.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/alex-de-minaur.jpg 1024w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/alex-de-minaur-300x200.jpg 300w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/alex-de-minaur-768px-512px.jpg 768w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/alex-de-minaur-180px-120px.jpg 180w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/alex-de-minaur-700px-466px.jpg 700w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/h2>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Tabla de contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/pokeriomokykla.com\/es\/atp-next-gen-final-alex-de-minaur-jannik-sinner-784046\/#Alex_De_Minaur\" >Alex De Minaur<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/pokeriomokykla.com\/es\/atp-next-gen-final-alex-de-minaur-jannik-sinner-784046\/#Jannik_Sinner\" >Jannik Sinner<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/pokeriomokykla.com\/es\/atp-next-gen-final-alex-de-minaur-jannik-sinner-784046\/#Historial_entre_ambos\" >Historial entre ambos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/pokeriomokykla.com\/es\/atp-next-gen-final-alex-de-minaur-jannik-sinner-784046\/#Pronostico\" >Pron\u00f3stico<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Alex_De_Minaur\"><\/span>Alex De Minaur<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"ltr\">De Minaur simplemente domina en este torneo: sigue siendo el \u00fanico jugador que a\u00fan no ha perdido en este torneo y, adem\u00e1s, lo ha hecho perdiendo solo 3 sets en 4 partidos jugados. El partido m\u00e1s tenso que tuvo que jugar el australiano fue la semifinal contra F. Tiafoe, en la que, ganando 2-0 en sets, perdi\u00f3 el tercer set en blanco, pero se rehabilit\u00f3 en el cuarto set y celebr\u00f3 la victoria. En ese partido, De Minaur gan\u00f3 el 40% de los puntos despu\u00e9s del saque del estadounidense, lo cual es una cifra incre\u00edblemente alta y muestra lo bien que juega el australiano en defensa. Alex tambi\u00e9n aprovech\u00f3 todas las oportunidades de break, utilizando las 4 oportunidades que tuvo para ganar el saque del oponente. Teniendo en cuenta lo fuerte que ha estado el australiano durante toda la temporada y lo dominante que se ve en este torneo, es el claro favorito para ganar este torneo.<\/p>\n<p dir=\"ltr\"><img decoding=\"async\" class=\"alignleft size-full wp-image-759771\" src=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature.jpg 1920w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-300x169.jpg 300w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-768px-432px.jpg 768w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-1536px-864px.jpg 1536w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-320px-180px.jpg 320w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-120px-68px.jpg 120w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-336px-188px.jpg 336w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-213px-120px.jpg 213w, https:\/\/pokeriomokykla.com\/app\/uploads\/2019\/11\/sinner-us-open-2019-feature-700px-394px.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Jannik_Sinner\"><\/span>Jannik Sinner<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El italiano tambi\u00e9n est\u00e1 jugando un buen torneo, pero durante la temporada no ha sido tan dominante como su oponente de hoy. Sinner lleg\u00f3 a la final despu\u00e9s de una dura batalla de 4 sets contra el serbio M. Kecmanovic. Aunque el italiano comenz\u00f3 mal el partido y perdi\u00f3 el primer set, se rehabilit\u00f3 en el siguiente set y gan\u00f3 el partido 3-1. Impresionante en ese partido fue tambi\u00e9n el porcentaje de primer servicio del italiano, que alcanz\u00f3 el 70% y le permiti\u00f3 ganar el 90% de los puntos despu\u00e9s del primer servicio. En cualquier caso, hoy le espera el partido m\u00e1s dif\u00edcil de este torneo, en el que para ganar, el italiano tendr\u00e1 que mostrar mucho m\u00e1s que en los partidos anteriores.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Historial_entre_ambos\"><\/span>Historial entre ambos<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p dir=\"ltr\">Estos j\u00f3venes jugadores a\u00fan no han jugado uno contra el otro en partidos oficiales de la ATP, y esta ser\u00e1 la primera vez.<\/p>\n<div class=\"align-left inline-promo\">\n<h2 id=\"ad_article_300x250_1\" class=\"promo promo-all active\"><span class=\"ez-toc-section\" id=\"Pronostico\"><\/span><span style=\"font-size: 1.5em;\">Pron\u00f3stico<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<\/div>\n<p dir=\"ltr\">El italiano J. Sinner sin duda recibir\u00e1 el apoyo del p\u00fablico, ya que el partido se jugar\u00e1 en Italia. Esto podr\u00eda ayudarle a ganar m\u00e1s puntos de lo que se podr\u00eda esperar en otras circunstancias, pero teniendo en cuenta lo imparable que parece el australiano, los espectadores probablemente se sentir\u00e1n decepcionados. De Minaur es hoy en d\u00eda un jugador mucho m\u00e1s fuerte y deber\u00eda demostrarlo esta noche, ganando uno de los t\u00edtulos m\u00e1s importantes de la temporada.<\/p>\n<h3 style=\"text-align: center;\">TOP Casas de Apuestas para apuestas NBA<\/h3>\n\n<div class='widget-card placeholder--card'\n     data-source-gql='https:\/\/scg-new-live.stellate.sh\/'\n     data-source-widgetjs='https:\/\/widget.affprojects.com\/widget.js'\n     data-shortcode='widget-card'\n     data-shortcode-text='[top-bookmakers-for-post]'\n     data-props='{\n\"show_more_button\":true,\n\"show_more_button_text\":\"Show More Bookmakers\",\n\"show_more_text\":false,\n\"show_less_text\":false,\n\"vpn_notification\":false,\n\"show_more_items_amount\":null,\n\"scrollable\":\"always\",\n\"violet_bonus_text\":true,\n\"ab_testing_show_more_button_rework\":true\n}'\n     data-queries='{\n\"type\":\"TOP-Betting\",\n\"limit\":10,\n\"mobile_limit\":10,\n\"show_new\":1,\n\"button_text_type\":\"TOP\",\n\"language\":\"es\",\n\"project\":\"PM\",\n\"page\":1\n}'\n     ><\/div>\n\n<p dir=\"ltr\">\n","protected":false},"excerpt":{"rendered":"<p>Alex De Minaur De Minaur simplemente domina en este torneo:&#8230;<\/p>\n","protected":false},"author":7495,"featured_media":759769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2089,1885,1903,1],"tags":[],"class_list":["post-784046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apuestas","category-pronosticos-de-apuestas","category-pronosticos-de-tenis","category-uncategorized-lt"],"acf":[],"_links":{"self":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts\/784046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/users\/7495"}],"replies":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/comments?post=784046"}],"version-history":[{"count":2,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts\/784046\/revisions"}],"predecessor-version":[{"id":1101047,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/posts\/784046\/revisions\/1101047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/media\/759769"}],"wp:attachment":[{"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/media?parent=784046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/categories?post=784046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pokeriomokykla.com\/es\/wp-json\/wp\/v2\/tags?post=784046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}